{"id":1543,"date":"2022-06-23T07:54:20","date_gmt":"2022-06-23T07:54:20","guid":{"rendered":"https:\/\/www.campariacademy.com\/it-it\/?p=1543"},"modified":"2022-07-13T03:44:54","modified_gmt":"2022-07-13T01:44:54","slug":"pitanti-tecniche-di-preparazione-dei-cocktail","status":"publish","type":"post","link":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/","title":{"rendered":"Pitanti: Tecniche Di Preparazione Dei Cocktail"},"content":{"rendered":"\n<p>Chi punta all\u2019eccellenza insegue la perfezione. Chi punta all\u2019eccellenza non smette mai di scoprire, di approfondire, di conoscere. Con le Masterclass di Campari Academy, ogni appuntamento \u00e8 un\u2019occasione di crescita. Insieme ad Alessandro Pitanti, nella Masterclass online analizzeremo le tecniche di miscelazione, con un focus sui cocktail pi\u00f9 iconici: storia, ricette, curiosit\u00e0 e tips &amp; tricks per realizzare cocktail perfetti e migliorare le proprie abilit\u00e0 di bartender.&nbsp;<\/p>\n\n\n\n<p>Alessandro Pitanti ci guida nell\u2019analisi dei tools e delle tecniche per esplorare i segreti della miscelazione: cenni storici e curiosit\u00e0 sui cocktail pi\u00f9 famosi, ma anche ricette approfondite, dettagli tecnici e consigli per realizzare qualsiasi drink in modo impeccabile.<br><strong>Programma<\/strong><\/p>\n\n\n\n<p>\u2022 La miscelazione<br>\u2022 I cocktail: Americano, Manhattan, Campari Shakerato, Red Snapper<br>\u2022 Le tecniche: Build, Stir, Shake, Throwing<\/p>\n\n\n\n<p><strong>Alessandro Pitanti<\/strong><\/p>\n\n\n\n<p>Nato nel 1989, Alessandro Pitanti \u00e8 un bartender con pi\u00f9 di 10 anni di esperienza. Cresce professionalmente a Forte dei Marmi, Londra (London Edition Hotel), Firenze (Four Seasons Hotel) e Pietrasanta (Filippo Mud). Il suo incontro con Campari avviene nel 2017, quando vince la Campari Barman Competition. Oggi \u00e8 Master Bartender di Campari Academy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi punta all\u2019eccellenza insegue la perfezione. Chi punta all\u2019eccellenza non smette mai di scoprire, di approfondire, di conoscere. Con le Masterclass di Campari Academy, ogni appuntamento \u00e8 un\u2019occasione di crescita. Insieme ad Alessandro Pitanti, nella Masterclass online analizzeremo le tecniche di miscelazione, con un focus sui cocktail pi\u00f9 iconici: storia, ricette, curiosit\u00e0 e tips &amp; [&hellip;]<\/p>\n","protected":false},"author":132,"featured_media":1436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24,21],"tags":[],"theme":[],"class_list":["post-1543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categorie-prodotti","category-training"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pitanti: Tecniche Di Preparazione Dei Cocktail - Campari Academy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pitanti: Tecniche Di Preparazione Dei Cocktail - Campari Academy\" \/>\n<meta property=\"og:description\" content=\"Chi punta all\u2019eccellenza insegue la perfezione. Chi punta all\u2019eccellenza non smette mai di scoprire, di approfondire, di conoscere. Con le Masterclass di Campari Academy, ogni appuntamento \u00e8 un\u2019occasione di crescita. Insieme ad Alessandro Pitanti, nella Masterclass online analizzeremo le tecniche di miscelazione, con un focus sui cocktail pi\u00f9 iconici: storia, ricette, curiosit\u00e0 e tips &amp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\" \/>\n<meta property=\"og:site_name\" content=\"Campari Academy\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T07:54:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-13T01:44:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto Zanardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto Zanardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\"},\"author\":{\"name\":\"Alberto Zanardo\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/person\/f40f63200e8ac7673f02f1f3417407cf\"},\"headline\":\"Pitanti: Tecniche Di Preparazione Dei Cocktail\",\"datePublished\":\"2022-06-23T07:54:20+00:00\",\"dateModified\":\"2022-07-13T01:44:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\"},\"wordCount\":184,\"publisher\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg\",\"articleSection\":[\"Categorie e Prodotti\",\"Training\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\",\"url\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\",\"name\":\"Pitanti: Tecniche Di Preparazione Dei Cocktail - Campari Academy\",\"isPartOf\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg\",\"datePublished\":\"2022-06-23T07:54:20+00:00\",\"dateModified\":\"2022-07-13T01:44:54+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage\",\"url\":\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg\",\"contentUrl\":\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#website\",\"url\":\"https:\/\/www.campariacademy.com\/it-it\/\",\"name\":\"Campari Academy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campariacademy.com\/it-it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#organization\",\"name\":\"Campari Academy\",\"url\":\"https:\/\/www.campariacademy.com\/it-it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/07\/campariacademy-logo.jpeg\",\"contentUrl\":\"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/07\/campariacademy-logo.jpeg\",\"width\":500,\"height\":185,\"caption\":\"Campari Academy\"},\"image\":{\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/person\/f40f63200e8ac7673f02f1f3417407cf\",\"name\":\"Alberto Zanardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dbcad150c96422bf8c2abd3dcffdbd849baf388a48e28b0567b482ff96764fae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dbcad150c96422bf8c2abd3dcffdbd849baf388a48e28b0567b482ff96764fae?s=96&d=mm&r=g\",\"caption\":\"Alberto Zanardo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pitanti: Tecniche Di Preparazione Dei Cocktail - Campari Academy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/","og_locale":"it_IT","og_type":"article","og_title":"Pitanti: Tecniche Di Preparazione Dei Cocktail - Campari Academy","og_description":"Chi punta all\u2019eccellenza insegue la perfezione. Chi punta all\u2019eccellenza non smette mai di scoprire, di approfondire, di conoscere. Con le Masterclass di Campari Academy, ogni appuntamento \u00e8 un\u2019occasione di crescita. Insieme ad Alessandro Pitanti, nella Masterclass online analizzeremo le tecniche di miscelazione, con un focus sui cocktail pi\u00f9 iconici: storia, ricette, curiosit\u00e0 e tips &amp; [&hellip;]","og_url":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/","og_site_name":"Campari Academy","article_published_time":"2022-06-23T07:54:20+00:00","article_modified_time":"2022-07-13T01:44:54+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg","type":"image\/jpeg"}],"author":"Alberto Zanardo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Alberto Zanardo","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#article","isPartOf":{"@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/"},"author":{"name":"Alberto Zanardo","@id":"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/person\/f40f63200e8ac7673f02f1f3417407cf"},"headline":"Pitanti: Tecniche Di Preparazione Dei Cocktail","datePublished":"2022-06-23T07:54:20+00:00","dateModified":"2022-07-13T01:44:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/"},"wordCount":184,"publisher":{"@id":"https:\/\/www.campariacademy.com\/it-it\/#organization"},"image":{"@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg","articleSection":["Categorie e Prodotti","Training"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/","url":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/","name":"Pitanti: Tecniche Di Preparazione Dei Cocktail - Campari Academy","isPartOf":{"@id":"https:\/\/www.campariacademy.com\/it-it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage"},"image":{"@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg","datePublished":"2022-06-23T07:54:20+00:00","dateModified":"2022-07-13T01:44:54+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.campariacademy.com\/it-it\/training\/pitanti-tecniche-di-preparazione-dei-cocktail\/#primaryimage","url":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg","contentUrl":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/06\/PITANTI_-TECNICHE-DI-PREPARAZIONE-DEI-COCKTAIL-e1655891638893.jpg","width":1024,"height":683},{"@type":"WebSite","@id":"https:\/\/www.campariacademy.com\/it-it\/#website","url":"https:\/\/www.campariacademy.com\/it-it\/","name":"Campari Academy","description":"","publisher":{"@id":"https:\/\/www.campariacademy.com\/it-it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campariacademy.com\/it-it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.campariacademy.com\/it-it\/#organization","name":"Campari Academy","url":"https:\/\/www.campariacademy.com\/it-it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/logo\/image\/","url":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/07\/campariacademy-logo.jpeg","contentUrl":"https:\/\/www.campariacademy.com\/it-it\/wp-content\/uploads\/sites\/2\/2022\/07\/campariacademy-logo.jpeg","width":500,"height":185,"caption":"Campari Academy"},"image":{"@id":"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/person\/f40f63200e8ac7673f02f1f3417407cf","name":"Alberto Zanardo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.campariacademy.com\/it-it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dbcad150c96422bf8c2abd3dcffdbd849baf388a48e28b0567b482ff96764fae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dbcad150c96422bf8c2abd3dcffdbd849baf388a48e28b0567b482ff96764fae?s=96&d=mm&r=g","caption":"Alberto Zanardo"}}]}},"_links":{"self":[{"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/posts\/1543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/users\/132"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/comments?post=1543"}],"version-history":[{"count":4,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/posts\/1543\/revisions"}],"predecessor-version":[{"id":1586,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/posts\/1543\/revisions\/1586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/media\/1436"}],"wp:attachment":[{"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/media?parent=1543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/categories?post=1543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/tags?post=1543"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/www.campariacademy.com\/it-it\/wp-json\/wp\/v2\/theme?post=1543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}